{"id":2968,"date":"2022-08-03T07:25:22","date_gmt":"2022-08-03T05:25:22","guid":{"rendered":"https:\/\/jachtenschietsportaalten.nl\/product\/fabarm-nobille-2\/"},"modified":"2024-09-11T18:05:56","modified_gmt":"2024-09-11T16:05:56","slug":"fabarm-nobille-2","status":"publish","type":"product","link":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/","title":{"rendered":"Fabarm Nobille 2"},"content":{"rendered":"<p>Fabarm ist eine italienische Marke, die derzeit zur Beretta-Gruppe geh\u00f6rt. Die Fabarm Nobille 2 ist eine Side-by-Side im Kaliber .20. Das Besondere an diesem Gewehr ist, dass es ein klassisches Aussehen hat, aber ultramodern ist, u.a. mit Schaltchokes, Einzelabzug und geeignet f\u00fcr Stahlmunition.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabarm ist eine italienische Marke, die derzeit zur Beretta-Gruppe geh\u00f6rt. Die Fabarm Nobille 2 ist eine Side-by-Side im Kaliber .20. Das Besondere an diesem Gewehr ist, dass es ein klassisches Aussehen hat, aber ultramodern ist, u.a. mit Schaltchokes, Einzelabzug und geeignet f\u00fcr Stahlmunition.<\/p>\n","protected":false},"featured_media":1619,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[566],"product_tag":[],"class_list":{"0":"post-2968","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-keine-kategorie","7":"entry","8":"has-media","10":"first","11":"outofstock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabarm Nobille 2 - Jacht en Schietsport Aalten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabarm Nobille 2 - Jacht en Schietsport Aalten\" \/>\n<meta property=\"og:description\" content=\"Fabarm ist eine italienische Marke, die derzeit zur Beretta-Gruppe geh\u00f6rt. Die Fabarm Nobille 2 ist eine Side-by-Side im Kaliber .20. Das Besondere an diesem Gewehr ist, dass es ein klassisches Aussehen hat, aber ultramodern ist, u.a. mit Schaltchokes, Einzelabzug und geeignet f\u00fcr Stahlmunition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacht en Schietsport Aalten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T16:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-001-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/\",\"name\":\"Fabarm Nobille 2 - Jacht en Schietsport Aalten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-001-1.jpg\",\"datePublished\":\"2022-08-03T05:25:22+00:00\",\"dateModified\":\"2024-09-11T16:05:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-001-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-001-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/fabarm-nobille-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fabarm Nobille 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"name\":\"Jacht en Schietsport Aalten\",\"description\":\"Webshop\",\"publisher\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\",\"name\":\"Jacht en Schietsport Aalten\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"width\":2212,\"height\":679,\"caption\":\"Jacht en Schietsport Aalten\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabarm Nobille 2 - Jacht en Schietsport Aalten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/","og_locale":"de_DE","og_type":"article","og_title":"Fabarm Nobille 2 - Jacht en Schietsport Aalten","og_description":"Fabarm ist eine italienische Marke, die derzeit zur Beretta-Gruppe geh\u00f6rt. Die Fabarm Nobille 2 ist eine Side-by-Side im Kaliber .20. Das Besondere an diesem Gewehr ist, dass es ein klassisches Aussehen hat, aber ultramodern ist, u.a. mit Schaltchokes, Einzelabzug und geeignet f\u00fcr Stahlmunition.","og_url":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/","og_site_name":"Jacht en Schietsport Aalten","article_modified_time":"2024-09-11T16:05:56+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-001-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/","url":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/","name":"Fabarm Nobille 2 - Jacht en Schietsport Aalten","isPartOf":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/#primaryimage"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/#primaryimage"},"thumbnailUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-001-1.jpg","datePublished":"2022-08-03T05:25:22+00:00","dateModified":"2024-09-11T16:05:56+00:00","breadcrumb":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/#primaryimage","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-001-1.jpg","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-001-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/fabarm-nobille-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jachtenschietsportaalten.nl\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/jachtenschietsportaalten.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Fabarm Nobille 2"}]},{"@type":"WebSite","@id":"https:\/\/jachtenschietsportaalten.nl\/#website","url":"https:\/\/jachtenschietsportaalten.nl\/","name":"Jacht en Schietsport Aalten","description":"Webshop","publisher":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jachtenschietsportaalten.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jachtenschietsportaalten.nl\/#organization","name":"Jacht en Schietsport Aalten","url":"https:\/\/jachtenschietsportaalten.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","width":2212,"height":679,"caption":"Jacht en Schietsport Aalten"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product\/2968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/comments?post=2968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/media\/1619"}],"wp:attachment":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/media?parent=2968"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_brand?post=2968"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_cat?post=2968"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_tag?post=2968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}