{"id":2983,"date":"2022-08-03T07:25:27","date_gmt":"2022-08-03T05:25:27","guid":{"rendered":"https:\/\/jachtenschietsportaalten.nl\/product\/beretta-a-400-explorer\/"},"modified":"2024-10-22T14:32:05","modified_gmt":"2024-10-22T12:32:05","slug":"beretta-a-400-explorer","status":"publish","type":"product","link":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/","title":{"rendered":"Beretta A 400 Explorer"},"content":{"rendered":"<p>Sch\u00f6ne Ausf\u00fchrung des A 400 in der Explorer-Version. Dieses Gewehr verf\u00fcgt \u00fcber eine Reihe einzigartiger Ausstattungsmerkmale wie: Ipod-System zur Verfolgung der Schusszahl und -f\u00fchrung, ein Kickoff-System, bei dem der R\u00fccksto\u00df um 70 % reduziert ist, und ein Switchchoke-System. Das Holz wird mit dem Laser bearbeitet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sch\u00f6ne Ausf\u00fchrung des A 400 in der Explorer-Version. Dieses Gewehr verf\u00fcgt \u00fcber eine Reihe einzigartiger Ausstattungsmerkmale wie: Ipod-System zur Verfolgung der Schusszahl und -f\u00fchrung, ein Kickoff-System, bei dem der R\u00fccksto\u00df um 70 % reduziert ist, und ein Switchchoke-System. Das Holz wird mit dem Laser bearbeitet.<\/p>\n","protected":false},"featured_media":1796,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[1332],"product_tag":[],"class_list":{"0":"post-2983","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schrotflinte-de","7":"entry","8":"has-media","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beretta A 400 Explorer - Jacht en Schietsport Aalten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beretta A 400 Explorer - Jacht en Schietsport Aalten\" \/>\n<meta property=\"og:description\" content=\"Sch\u00f6ne Ausf\u00fchrung des A 400 in der Explorer-Version. Dieses Gewehr verf\u00fcgt \u00fcber eine Reihe einzigartiger Ausstattungsmerkmale wie: Ipod-System zur Verfolgung der Schusszahl und -f\u00fchrung, ein Kickoff-System, bei dem der R\u00fccksto\u00df um 70 % reduziert ist, und ein Switchchoke-System. Das Holz wird mit dem Laser bearbeitet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacht en Schietsport Aalten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T12:32:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-076-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/\",\"name\":\"Beretta A 400 Explorer - Jacht en Schietsport Aalten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-076-1.jpg\",\"datePublished\":\"2022-08-03T05:25:27+00:00\",\"dateModified\":\"2024-10-22T12:32:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-076-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-076-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/produkt\\\/beretta-a-400-explorer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beretta A 400 Explorer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"name\":\"Jacht en Schietsport Aalten\",\"description\":\"Webshop\",\"publisher\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\",\"name\":\"Jacht en Schietsport Aalten\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"width\":2212,\"height\":679,\"caption\":\"Jacht en Schietsport Aalten\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beretta A 400 Explorer - Jacht en Schietsport Aalten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/","og_locale":"de_DE","og_type":"article","og_title":"Beretta A 400 Explorer - Jacht en Schietsport Aalten","og_description":"Sch\u00f6ne Ausf\u00fchrung des A 400 in der Explorer-Version. Dieses Gewehr verf\u00fcgt \u00fcber eine Reihe einzigartiger Ausstattungsmerkmale wie: Ipod-System zur Verfolgung der Schusszahl und -f\u00fchrung, ein Kickoff-System, bei dem der R\u00fccksto\u00df um 70 % reduziert ist, und ein Switchchoke-System. Das Holz wird mit dem Laser bearbeitet.","og_url":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/","og_site_name":"Jacht en Schietsport Aalten","article_modified_time":"2024-10-22T12:32:05+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-076-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/","url":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/","name":"Beretta A 400 Explorer - Jacht en Schietsport Aalten","isPartOf":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/#primaryimage"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/#primaryimage"},"thumbnailUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-076-1.jpg","datePublished":"2022-08-03T05:25:27+00:00","dateModified":"2024-10-22T12:32:05+00:00","breadcrumb":{"@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/#primaryimage","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-076-1.jpg","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-076-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/jachtenschietsportaalten.nl\/de\/produkt\/beretta-a-400-explorer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jachtenschietsportaalten.nl\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/jachtenschietsportaalten.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Beretta A 400 Explorer"}]},{"@type":"WebSite","@id":"https:\/\/jachtenschietsportaalten.nl\/#website","url":"https:\/\/jachtenschietsportaalten.nl\/","name":"Jacht en Schietsport Aalten","description":"Webshop","publisher":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jachtenschietsportaalten.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jachtenschietsportaalten.nl\/#organization","name":"Jacht en Schietsport Aalten","url":"https:\/\/jachtenschietsportaalten.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","width":2212,"height":679,"caption":"Jacht en Schietsport Aalten"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product\/2983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/comments?post=2983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/media\/1796"}],"wp:attachment":[{"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/media?parent=2983"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_brand?post=2983"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_cat?post=2983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/de\/wp-json\/wp\/v2\/product_tag?post=2983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}