{"id":4247,"date":"2022-08-03T07:25:21","date_gmt":"2022-08-03T05:25:21","guid":{"rendered":"https:\/\/jachtenschietsportaalten.nl\/product\/webley-scotty\/"},"modified":"2024-10-23T10:44:01","modified_gmt":"2024-10-23T08:44:01","slug":"webley-scotty","status":"publish","type":"product","link":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/","title":{"rendered":"Webley &amp; Scotty"},"content":{"rendered":"<p>Beautiful English side by side rifle for the enthusiast. Chambers are lengthened to 70 mm, beautiful wood including original case. Flask length 35.5 without and 40 cm with extension.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beautiful English side by side rifle for the enthusiast. Chambers are lengthened to 70 mm, beautiful wood including original case. Flask length 35.5 without and 40 cm with extension.<\/p>\n","protected":false},"featured_media":3833,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[1333],"product_tag":[],"class_list":{"0":"post-4247","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-shotgun-en-4","7":"entry","8":"has-media","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webley &amp; Scotty - Jacht en Schietsport Aalten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webley &amp; Scotty - Jacht en Schietsport Aalten\" \/>\n<meta property=\"og:description\" content=\"Beautiful English side by side rifle for the enthusiast. Chambers are lengthened to 70 mm, beautiful wood including original case. Flask length 35.5 without and 40 cm with extension.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacht en Schietsport Aalten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T08:44:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/20220524WH-048-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/\",\"name\":\"Webley &amp; Scotty - Jacht en Schietsport Aalten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/20220524WH-048-1.jpg\",\"datePublished\":\"2022-08-03T05:25:21+00:00\",\"dateModified\":\"2024-10-23T08:44:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/20220524WH-048-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/20220524WH-048-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/webley-scotty\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webley &amp; Scotty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"name\":\"Jacht en Schietsport Aalten\",\"description\":\"Webshop\",\"publisher\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\",\"name\":\"Jacht en Schietsport Aalten\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"width\":2212,\"height\":679,\"caption\":\"Jacht en Schietsport Aalten\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webley &amp; Scotty - Jacht en Schietsport Aalten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/","og_locale":"en_US","og_type":"article","og_title":"Webley &amp; Scotty - Jacht en Schietsport Aalten","og_description":"Beautiful English side by side rifle for the enthusiast. Chambers are lengthened to 70 mm, beautiful wood including original case. Flask length 35.5 without and 40 cm with extension.","og_url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/","og_site_name":"Jacht en Schietsport Aalten","article_modified_time":"2024-10-23T08:44:01+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/20220524WH-048-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/","url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/","name":"Webley &amp; Scotty - Jacht en Schietsport Aalten","isPartOf":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/#primaryimage"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/#primaryimage"},"thumbnailUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/20220524WH-048-1.jpg","datePublished":"2022-08-03T05:25:21+00:00","dateModified":"2024-10-23T08:44:01+00:00","breadcrumb":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/#primaryimage","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/20220524WH-048-1.jpg","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/20220524WH-048-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/webley-scotty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jachtenschietsportaalten.nl\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/jachtenschietsportaalten.nl\/en\/webshop\/"},{"@type":"ListItem","position":3,"name":"Webley &amp; Scotty"}]},{"@type":"WebSite","@id":"https:\/\/jachtenschietsportaalten.nl\/#website","url":"https:\/\/jachtenschietsportaalten.nl\/","name":"Jacht en Schietsport Aalten","description":"Webshop","publisher":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jachtenschietsportaalten.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jachtenschietsportaalten.nl\/#organization","name":"Jacht en Schietsport Aalten","url":"https:\/\/jachtenschietsportaalten.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","width":2212,"height":679,"caption":"Jacht en Schietsport Aalten"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product\/4247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/comments?post=4247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media\/3833"}],"wp:attachment":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media?parent=4247"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_brand?post=4247"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_cat?post=4247"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_tag?post=4247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}