{"id":4259,"date":"2022-08-03T07:25:23","date_gmt":"2022-08-03T05:25:23","guid":{"rendered":"https:\/\/jachtenschietsportaalten.nl\/product\/fn-b25-stairs\/"},"modified":"2024-03-23T12:55:46","modified_gmt":"2024-03-23T10:55:46","slug":"fn-b25-stage","status":"publish","type":"product","link":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/","title":{"rendered":"FN B25 Stairs"},"content":{"rendered":"<p>FN B25 in the Staircase version, so 81 cm barrel with 3\/4-1\/1 chokes and wide 16 mm piping. Pistol grip still features a small &#8220;Kaisergriff&#8221; in ebony.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FN B25 in the Staircase version, so 81 cm barrel with 3\/4-1\/1 chokes and wide 16 mm piping. Pistol grip still features a small &#8220;Kaisergriff&#8221; in ebony.<\/p>\n","protected":false},"featured_media":3883,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-4259","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-geen-categorie","7":"entry","8":"has-media","10":"first","11":"outofstock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FN B25 Stairs - Jacht en Schietsport Aalten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FN B25 Stairs - Jacht en Schietsport Aalten\" \/>\n<meta property=\"og:description\" content=\"FN B25 in the Staircase version, so 81 cm barrel with 3\/4-1\/1 chokes and wide 16 mm piping. Pistol grip still features a small &#8220;Kaisergriff&#8221; in ebony.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacht en Schietsport Aalten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-23T10:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-010-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/\",\"name\":\"FN B25 Stairs - Jacht en Schietsport Aalten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-010-1.jpg\",\"datePublished\":\"2022-08-03T05:25:23+00:00\",\"dateModified\":\"2024-03-23T10:55:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-010-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/220720WH-010-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/fn-b25-stage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FN B25 Stairs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"name\":\"Jacht en Schietsport Aalten\",\"description\":\"Webshop\",\"publisher\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\",\"name\":\"Jacht en Schietsport Aalten\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"width\":2212,\"height\":679,\"caption\":\"Jacht en Schietsport Aalten\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FN B25 Stairs - Jacht en Schietsport Aalten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/","og_locale":"en_US","og_type":"article","og_title":"FN B25 Stairs - Jacht en Schietsport Aalten","og_description":"FN B25 in the Staircase version, so 81 cm barrel with 3\/4-1\/1 chokes and wide 16 mm piping. Pistol grip still features a small &#8220;Kaisergriff&#8221; in ebony.","og_url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/","og_site_name":"Jacht en Schietsport Aalten","article_modified_time":"2024-03-23T10:55:46+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-010-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/","url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/","name":"FN B25 Stairs - Jacht en Schietsport Aalten","isPartOf":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/#primaryimage"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/#primaryimage"},"thumbnailUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-010-1.jpg","datePublished":"2022-08-03T05:25:23+00:00","dateModified":"2024-03-23T10:55:46+00:00","breadcrumb":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/#primaryimage","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-010-1.jpg","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/220720WH-010-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/fn-b25-stage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jachtenschietsportaalten.nl\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/jachtenschietsportaalten.nl\/en\/webshop\/"},{"@type":"ListItem","position":3,"name":"FN B25 Stairs"}]},{"@type":"WebSite","@id":"https:\/\/jachtenschietsportaalten.nl\/#website","url":"https:\/\/jachtenschietsportaalten.nl\/","name":"Jacht en Schietsport Aalten","description":"Webshop","publisher":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jachtenschietsportaalten.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jachtenschietsportaalten.nl\/#organization","name":"Jacht en Schietsport Aalten","url":"https:\/\/jachtenschietsportaalten.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","width":2212,"height":679,"caption":"Jacht en Schietsport Aalten"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product\/4259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/comments?post=4259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media\/3883"}],"wp:attachment":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media?parent=4259"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_brand?post=4259"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_cat?post=4259"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_tag?post=4259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}