{"id":4604,"date":"2023-04-12T10:47:52","date_gmt":"2023-04-12T08:47:52","guid":{"rendered":"https:\/\/jachtenschietsportaalten.nl\/product\/blaser-f3\/"},"modified":"2024-03-02T19:49:37","modified_gmt":"2024-03-02T17:49:37","slug":"blaser-f3","status":"publish","type":"product","link":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/","title":{"rendered":"Blaser F3"},"content":{"rendered":"<p>Blaser F3 with 72 cm barrel fitted with swap chokes, incl Blaser case<\/p>\n","protected":false},"excerpt":{"rendered":"<p>          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4595\" src=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-300x300.jpg 300w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-1024x1024.jpg 1024w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-150x150.jpg 150w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-768x768.jpg 768w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-1536x1536.jpg 1536w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-600x600.jpg 600w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1-100x100.jpg 100w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil-1.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4598\" src=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-300x300.jpg 300w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-1024x1024.jpg 1024w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-150x150.jpg 150w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-768x768.jpg 768w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-1536x1536.jpg 1536w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-600x600.jpg 600w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2-100x100.jpg 100w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH030-Voskuil-2.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4601\" src=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-300x300.jpg 300w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-1024x1024.jpg 1024w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-150x150.jpg 150w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-768x768.jpg 768w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-1536x1536.jpg 1536w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-600x600.jpg 600w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil-100x100.jpg 100w, https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH028-Voskuil.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"featured_media":4581,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[35],"product_tag":[],"class_list":{"0":"post-4604","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-geen-categorie","7":"entry","8":"has-media","10":"first","11":"outofstock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blaser F3 - Jacht en Schietsport Aalten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blaser F3 - Jacht en Schietsport Aalten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/\" \/>\n<meta property=\"og:site_name\" content=\"Jacht en Schietsport Aalten\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T17:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/\",\"name\":\"Blaser F3 - Jacht en Schietsport Aalten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/02222023WH029-Voskuil.jpg\",\"datePublished\":\"2023-04-12T08:47:52+00:00\",\"dateModified\":\"2024-03-02T17:49:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/02222023WH029-Voskuil.jpg\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/02222023WH029-Voskuil.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/product\\\/blaser-f3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/en\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blaser F3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#website\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"name\":\"Jacht en Schietsport Aalten\",\"description\":\"Webshop\",\"publisher\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#organization\",\"name\":\"Jacht en Schietsport Aalten\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"contentUrl\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Voskuil_Logo_CMYK-Liggend_02.png\",\"width\":2212,\"height\":679,\"caption\":\"Jacht en Schietsport Aalten\"},\"image\":{\"@id\":\"https:\\\/\\\/jachtenschietsportaalten.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blaser F3 - Jacht en Schietsport Aalten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/","og_locale":"en_US","og_type":"article","og_title":"Blaser F3 - Jacht en Schietsport Aalten","og_url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/","og_site_name":"Jacht en Schietsport Aalten","article_modified_time":"2024-03-02T17:49:37+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/","url":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/","name":"Blaser F3 - Jacht en Schietsport Aalten","isPartOf":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/#primaryimage"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/#primaryimage"},"thumbnailUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil.jpg","datePublished":"2023-04-12T08:47:52+00:00","dateModified":"2024-03-02T17:49:37+00:00","breadcrumb":{"@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/#primaryimage","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil.jpg","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2023\/04\/02222023WH029-Voskuil.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/jachtenschietsportaalten.nl\/en\/product\/blaser-f3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jachtenschietsportaalten.nl\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/jachtenschietsportaalten.nl\/en\/webshop\/"},{"@type":"ListItem","position":3,"name":"Blaser F3"}]},{"@type":"WebSite","@id":"https:\/\/jachtenschietsportaalten.nl\/#website","url":"https:\/\/jachtenschietsportaalten.nl\/","name":"Jacht en Schietsport Aalten","description":"Webshop","publisher":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jachtenschietsportaalten.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jachtenschietsportaalten.nl\/#organization","name":"Jacht en Schietsport Aalten","url":"https:\/\/jachtenschietsportaalten.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/","url":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","contentUrl":"https:\/\/jachtenschietsportaalten.nl\/wp-content\/uploads\/2022\/08\/Voskuil_Logo_CMYK-Liggend_02.png","width":2212,"height":679,"caption":"Jacht en Schietsport Aalten"},"image":{"@id":"https:\/\/jachtenschietsportaalten.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product\/4604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/comments?post=4604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media\/4581"}],"wp:attachment":[{"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/media?parent=4604"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_brand?post=4604"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_cat?post=4604"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jachtenschietsportaalten.nl\/en\/wp-json\/wp\/v2\/product_tag?post=4604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}